{"id":70143,"date":"2024-02-28T13:34:43","date_gmt":"2024-02-28T13:34:43","guid":{"rendered":"https:\/\/www.expondo.co.uk\/inspirations\/czym-jest-spawanie-definicja-i-metody-spawania-metalu\/"},"modified":"2024-08-30T06:28:23","modified_gmt":"2024-08-30T06:28:23","slug":"was-ist-schweissen-definition-und-schweissmethoden","status":"publish","type":"post","link":"https:\/\/www.expondo.de\/inspirationen\/was-ist-schweissen-definition-und-schweissmethoden\/","title":{"rendered":"Schwei\u00dfen in der Metallverarbeitung\u00a0"},"content":{"rendered":"\n<p><strong>F\u00fcr die Metallverarbeitung formen und schneiden Sie nicht nur Metalle, sondern f\u00fcgen diese auch zusammen. Die g\u00e4ngigste Methode zum Verbinden von Metallen ist das Schwei\u00dfen. Was es mit dieser Methode auf sich hat, erfahren Sie in diesem Artikel.&nbsp;<\/strong>&nbsp;<\/p>\n\n\n<div class=\"wp-block-ub-table-of-contents-block ub_table-of-contents\" data-showtext=\"show\" data-hidetext=\"hide\" data-scrolltype=\"auto\" id=\"ub_table-of-contents-09d65680-7e75-4b02-a720-1879f44c14de\" data-initiallyhideonmobile=\"false\"\n                    data-initiallyshow=\"true\"><div class=\"ub_table-of-contents-header-container\"><div class=\"ub_table-of-contents-header\">\n                    <div class=\"ub_table-of-contents-title\"><\/div><\/div><\/div><div class=\"ub_table-of-contents-extra-container\"><div class=\"ub_table-of-contents-container ub_table-of-contents-1-column \"><ul><li><a href=https:\/\/www.expondo.de\/inspirationen\/was-ist-schweissen-definition-und-schweissmethoden\/#0-was-ist-schwei%C3%9Fen->Was ist Schwei\u00dfen?&nbsp;<\/a><\/li><li><a href=https:\/\/www.expondo.de\/inspirationen\/was-ist-schweissen-definition-und-schweissmethoden\/#1-arten-und-methoden-des-schwei%C3%9Fens->Arten und Methoden des Schwei\u00dfens&nbsp;<\/a><ul><li><a href=https:\/\/www.expondo.de\/inspirationen\/was-ist-schweissen-definition-und-schweissmethoden\/#2-das-wig-schwei%C3%9Fen->Das WIG-Schwei\u00dfen&nbsp;<\/a><\/li><li><a href=https:\/\/www.expondo.de\/inspirationen\/was-ist-schweissen-definition-und-schweissmethoden\/#3-die-migmag-schwei%C3%9Fmethode->Die MIG\/MAG-Schwei\u00dfmethode&nbsp;<\/a><\/li><li><a href=https:\/\/www.expondo.de\/inspirationen\/was-ist-schweissen-definition-und-schweissmethoden\/#4-mit-elektroden-schwei%C3%9Fen->Mit Elektroden Schwei\u00dfen&nbsp;<\/a><\/li><\/ul><\/li><li><a href=https:\/\/www.expondo.de\/inspirationen\/was-ist-schweissen-definition-und-schweissmethoden\/#5-was-muss-ich-beim-aluminiumschwei%C3%9Fen-beachten->Was muss ich beim Aluminiumschwei\u00dfen beachten?&nbsp;<\/a><\/li><li><a href=https:\/\/www.expondo.de\/inspirationen\/was-ist-schweissen-definition-und-schweissmethoden\/#6-wie-teuer-sind-professionelle-schwei%C3%9Farbeiten->Wie teuer sind professionelle Schwei\u00dfarbeiten?&nbsp;<\/a><\/li><li><a href=https:\/\/www.expondo.de\/inspirationen\/was-ist-schweissen-definition-und-schweissmethoden\/#7-was-ist-schwei%C3%9Fen-%E2%80%93-zusammenfassung->Was ist Schwei\u00dfen? \u2013 Zusammenfassung&nbsp;&nbsp;<\/a><\/li><\/ul><\/div><\/div><\/div>\n\n\n<h2 class=\"wp-block-heading\" id=\"0-was-ist-schwei%C3%9Fen-\">Was ist Schwei\u00dfen?&nbsp;<\/h2>\n\n\n\n<p>Beim Schwei\u00dfen nutzen Sie sehr hohe Temperaturen, um Metallteile zu schmelzen, die an der Kontaktstelle eine Verbindung eingehen. Je nach Technik verwenden Sie zus\u00e4tzliche Bindemittel in Form von Elektroden, Schwei\u00dfdr\u00e4hten oder speziellen St\u00e4ben. Diese verbinden sich mit dem geschmolzenen Metall und bilden nach dem Aush\u00e4rten die Schwei\u00dfnaht.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"1-arten-und-methoden-des-schwei%C3%9Fens-\">Arten und Methoden des Schwei\u00dfens&nbsp;<\/h2>\n\n\n\n<p>F\u00fcr das Zusammenf\u00fcgen von Metallen mit Hitze wurden seit seiner Erfindung verschiedene Arten und Methoden des Schwei\u00dfens entwickelt. Sie unterscheiden sich aufgrund der verwendeten Energiequellen oder der Art der Materialverarbeitung. Nach Energiearten lassen sich folgende Schwei\u00dfarten unterscheiden:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Gas \u2013 mit einer Gasflamme (z. B. Acetylen) erhitzen Sie die Kanten von Metallteilen, um Stahl und Nichteisenmetalle miteinander zu verbinden.&nbsp;<\/li>\n\n\n\n<li>Elektrisch \u2013 ein Lichtbogen, der zwischen Elektrode und Metallst\u00fcck entsteht, erzeugt die f\u00fcr das Schwei\u00dfen ben\u00f6tigte Hitze. Die Methode eignet sich f\u00fcr verschiedene Metalle mit einer Dicke von 1 &#8211; 80 mm.&nbsp;<\/li>\n\n\n\n<li>Thermit (Aluminothermie) \u2013 eine Mischung aus Eisenoxid und Aluminium wird entz\u00fcndet und reagiert stark exotherm. Dabei entsteht fl\u00fcssiger Stahl, mit dem Sie Eisenbahnschienen, Stahlstifte und Gusseisenelemente verbinden.&nbsp;<\/li>\n\n\n\n<li>Laser \u2013 mit diesem modernen Verfahren verbinden Sie Stahl, Nickel, Titan und schwer schmelzbare Metalle. Es basiert auf einem leistungsstarken koh\u00e4renten Lichtstrahl. Dieser erm\u00f6glicht das Schwei\u00dfen von Werkst\u00fccken in unterschiedlichen Formen und aus allen Schwei\u00dfpositionen heraus.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>In diesem Artikel stellen wir Ihnen das Elektroschwei\u00dfen vor. Es findet in vielen Branchen Einsatz, z. B. in der Automobilindustrie, im Maschinenbau und bei Heimwerken. Hierf\u00fcr verwenden Sie unterschiedliche <a href=\"https:\/\/www.expondo.de\/schweissgeraete\/\" target=\"_blank\" rel=\"noreferrer noopener\"><mdspan datatext=\"el1724998183304\" class=\"mdspan-comment\">Schwei\u00dfger\u00e4te<\/mdspan><\/a>. Das Elektroschwei\u00dfen wird in mehrere Methoden unterteilt: WIG, MIG\/MAG und MMA.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"2-das-wig-schwei%C3%9Fen-\">Das WIG-Schwei\u00dfen&nbsp;<\/h3>\n\n\n\n<p>F\u00fcr das WIG-Schwei\u00dfverfahren verwenden Sie im Gegensatz zu anderen Schwei\u00dfmethoden eine nicht schmelzende Wolframelektrode. Zwischen ihr und dem Werkst\u00fcck erzeugen Sie einen Lichtbogen mit einer sehr hohen Temperatur, die zum Schmelzen des Metalls erforderlich ist. F\u00fcr eine stabile Schwei\u00dfnaht wird h\u00e4ufig zus\u00e4tzliches Material in Form von Schwei\u00dfst\u00e4ben hinzugef\u00fcgt.&nbsp;<\/p>\n\n\n              <div id=\"expondo-products-block_b6973e14c27ef7ecef574c45238591e0\" class=\"expondo-block expondo-block--products\">\n          <div class=\"expondo-block__inner-container\">\n            <ul class=\"list list--products\">\n                              <li class=\"item\">\n                  <a href=\"\/stamos-eco-wig-schweissgeraet-200-a-230-v-puls-digital-2-4-takt-10020062\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10020062_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/stamos-eco-wig-schweissgeraet-200-a-230-v-puls-digital-2-4-takt-10020062\">\n                        WIG-Schwei\u00dfger\u00e4t &#8211; 200 A &#8211; 230 V &#8211; Puls &#8211; digital &#8211; 2\/4 Takt                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                                          <\/span>\n                                  <\/li>\n                              <li class=\"item\">\n                  <a href=\"\/stamos-basic-wig-schweissgeraet-250-a-230-v-tragbar-10020010\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10020010_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/stamos-basic-wig-schweissgeraet-250-a-230-v-tragbar-10020010\">\n                        WIG Schwei\u00dfger\u00e4t &#8211; 250 A &#8211; 230 V &#8211; tragbar                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                                          <\/span>\n                                  <\/li>\n                              <li class=\"item\">\n                  <a href=\"\/stamos-basic-wig-schweissgeraet-250-a-230-v-puls-10020011\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10020011_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/stamos-basic-wig-schweissgeraet-250-a-230-v-puls-10020011\">\n                        WIG Schwei\u00dfger\u00e4t &#8211; 250 A &#8211; 230 V &#8211; Puls                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                                          <\/span>\n                                  <\/li>\n                              <li class=\"item\">\n                  <a href=\"\/stamos-selection-wig-schweissgeraet-225-a-230-v-puls-2-4-takt-selection-10020037\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10020037_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/stamos-selection-wig-schweissgeraet-225-a-230-v-puls-2-4-takt-selection-10020037\">\n                        WIG Schwei\u00dfger\u00e4t &#8211; 225 A &#8211; 230 V &#8211; Puls &#8211; 2\/4 Takt &#8211; SELECTION                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                                          <\/span>\n                                  <\/li>\n                          <\/ul>\n          <\/div>\n        <\/div>\n        \n\n\n<p>Ein weiteres charakteristisches Merkmal <a href=\"https:\/\/www.expondo.de\/inspirationen\/wig-schweissen-von-den-anfaengen-bis-heute\/\" target=\"_blank\" rel=\"noreferrer noopener\"><mdspan datatext=\"el1724998458541\" class=\"mdspan-comment\">des WIG-Schwei\u00dfens<\/mdspan><\/a> ist die Verwendung von Inertgas. Es sch\u00fctzt das Schwei\u00dfbad, also das beim Erhitzen entstehende fl\u00fcssige Metall. Dadurch wird die Verbindung haltbarer und korrosionsbest\u00e4ndiger.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"3-die-migmag-schwei%C3%9Fmethode-\">Die MIG\/MAG-Schwei\u00dfmethode&nbsp;<\/h3>\n\n\n\n<p>Die <a href=\"https:\/\/www.expondo.de\/inspirationen\/mig-oder-mag-aufs-schutzgas-kommt-es-an\/\" target=\"_blank\" rel=\"noreferrer noopener\"><mdspan datatext=\"el1724998649280\" class=\"mdspan-comment\">Schwei\u00dfmethoden MIG<\/mdspan><\/a> und MAG werden oft zusammen genannt, weil sie sich nur in einer Sache unterscheiden. Bei beiden Techniken wird ein Schwei\u00dfdraht verwendet, um einen Lichtbogen zu erzeugen. Unter dem Einfluss der erzeugten W\u00e4rme schmilzt der Draht und erzeugt eine feste Schwei\u00dfnaht zwischen den Metallst\u00fccken.\u00a0<\/p>\n\n\n              <div id=\"expondo-products-block_2190475850c68a5f35c58b88174ba768\" class=\"expondo-block expondo-block--products\">\n          <div class=\"expondo-block__inner-container\">\n            <ul class=\"list list--products\">\n                              <li class=\"item\">\n                  <a href=\"\/stamos-selection-mig-mag-schweissgeraet-350-a-400-v-2-4-takt-10020080\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10020080_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/stamos-selection-mig-mag-schweissgeraet-350-a-400-v-2-4-takt-10020080\">\n                        MIG\/MAG Schwei\u00dfger\u00e4t &#8211; 350 A &#8211; 400 V &#8211; 2\/4 Takt                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                                          <\/span>\n                                  <\/li>\n                              <li class=\"item\">\n                  <a href=\"\/welbach-mig-mag-schweissgeraet-270-a-synergic-puls-e-hand-10021242\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10021242_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/welbach-mig-mag-schweissgeraet-270-a-synergic-puls-e-hand-10021242\">\n                        MIG\/MAG Schwei\u00dfger\u00e4t &#8211; 270 A &#8211; Synergic Puls &#8211; E-Hand                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                                          <\/span>\n                                  <\/li>\n                              <li class=\"item\">\n                  <a href=\"\/welbach-mig-mag-schweissgeraet-250-a-digital-e-hand-10021241\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10021241_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/welbach-mig-mag-schweissgeraet-250-a-digital-e-hand-10021241\">\n                        MIG\/MAG Schwei\u00dfger\u00e4t &#8211; 250 A &#8211; digital &#8211; E-Hand                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                                          <\/span>\n                                  <\/li>\n                              <li class=\"item\">\n                  <a href=\"\/stamos-basic-mig-mag-schweissgeraet-250-a-230-v-ed-60-10020022\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10020022_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/stamos-basic-mig-mag-schweissgeraet-250-a-230-v-ed-60-10020022\">\n                        MIG\/MAG Schwei\u00dfger\u00e4t &#8211; 250 A &#8211; 230 V &#8211; ED 60 %                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                                          <\/span>\n                                  <\/li>\n                          <\/ul>\n          <\/div>\n        <\/div>\n        \n\n\n<p>Der einzige Unterschied zwischen MIG und MAG ist das verwendete Schutzgas. F\u00fcr MIG verwenden Sie Inertgase wie Argon, f\u00fcr MAG aktive Gase wie Kohlendioxid. Ersteres reagiert nicht mit dem Metall im Schwei\u00dfbad, letzteres hingegen schon. Beide haben jedoch die gleiche Aufgabe \u2013 den Schutz der Schwei\u00dfnaht vor \u00e4u\u00dferen Einfl\u00fcssen.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"4-mit-elektroden-schwei%C3%9Fen-\">Mit Elektroden Schwei\u00dfen&nbsp;<\/h3>\n\n\n\n<p>Die letzte elektrische <a href=\"https:\/\/www.expondo.de\/schweissgeraete\/\" target=\"_blank\" rel=\"noreferrer noopener\"><mdspan datatext=\"el1724998726722\" class=\"mdspan-comment\">Schwei\u00dfmethode<\/mdspan><\/a> ist MMA oder E-Hand. Daf\u00fcr verwenden Sie eine umh\u00fcllte Elektrode aus einem Metallkern und einer Ummantelung, um eine Schwei\u00dfnaht herzustellen. W\u00e4hrend des Schwei\u00dfens schmilzt der Kern und aus der Au\u00dfenh\u00fclle werden Schutzgase freigesetzt. Dabei entsteht Schlacke, die auf der Schwei\u00dfnaht zur\u00fcckbleibt.\u00a0<\/p>\n\n\n              <div id=\"expondo-products-block_24c0a94d1ba5934b25adb78c2425de9f\" class=\"expondo-block expondo-block--products\">\n          <div class=\"expondo-block__inner-container\">\n            <ul class=\"list list--products\">\n                              <li class=\"item\">\n                  <a href=\"\/stamos-pro-series-elektroden-schweissgeraet-250-a-hot-start-igbt-pro-10020203\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10020203_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/stamos-pro-series-elektroden-schweissgeraet-250-a-hot-start-igbt-pro-10020203\">\n                        Elektroden-Schwei\u00dfger\u00e4t &#8211; 250 A &#8211; Hot Start &#8211; IGBT &#8211; PRO                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                              <ins>121.00&nbsp;\u20ac<\/ins>\n                    <\/span>\n                                  <\/li>\n                              <li class=\"item\">\n                  <a href=\"\/stamos-basic-elektroden-schweissgeraet-250-a-230-v-igbt-60-ed-10020135\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10020135_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/stamos-basic-elektroden-schweissgeraet-250-a-230-v-igbt-60-ed-10020135\">\n                        Elektroden-Schwei\u00dfger\u00e4t &#8211; 250 A &#8211; 230 V &#8211; IGBT &#8211; 60 % ED                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                                          <\/span>\n                                  <\/li>\n                              <li class=\"item\">\n                  <a href=\"\/stamos-germany-elektroden-schweissgeraet-200-a-hot-start-igbt-10020202\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10020202_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/stamos-germany-elektroden-schweissgeraet-200-a-hot-start-igbt-10020202\">\n                        Elektroden-Schwei\u00dfger\u00e4t &#8211; 200 A &#8211; Hot Start &#8211; IGBT                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                                          <\/span>\n                                  <\/li>\n                              <li class=\"item\">\n                  <a href=\"\/stamos-basic-elektroden-schweissgeraet-180-a-230-v-igbt-80-ed-10020017\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10020017_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/stamos-basic-elektroden-schweissgeraet-180-a-230-v-igbt-80-ed-10020017\">\n                        Elektroden-Schwei\u00dfger\u00e4t &#8211; 180 A &#8211; 230 V &#8211; IGBT &#8211; 80 % ED                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                                          <\/span>\n                                  <\/li>\n                          <\/ul>\n          <\/div>\n        <\/div>\n        \n\n\n<h2 class=\"wp-block-heading\" id=\"5-was-muss-ich-beim-aluminiumschwei%C3%9Fen-beachten-\">Was muss ich beim Aluminiumschwei\u00dfen beachten?&nbsp;<\/h2>\n\n\n\n<p>Beim Schwei\u00dfen verbinden Sie verschiedene Arten von Metallen und deren Legierungen miteinander. Einige Metallarten erfordern jedoch ausreichende Kenntnisse, um sicherzustellen, dass Sie den Grundwerkstoff nicht besch\u00e4digen und eine sehr haltbare Schwei\u00dfnaht erzielen. Ein hervorragendes Beispiel ist Aluminium.&nbsp;<\/p>\n\n\n\n<p>Die Schwierigkeit beim <a href=\"https:\/\/www.expondo.de\/inspirationen\/aluminium-schweissen-welches-schweissgeraet-soll-ich-waehlen\/\" target=\"_blank\" rel=\"noreferrer noopener\"><mdspan datatext=\"el1724998819883\" class=\"mdspan-comment\">Schwei\u00dfen von Aluminium<\/mdspan><\/a> ist sein relativ niedriger Schmelzpunkt. Das bedeutet, dass Sie bei schlecht eingestellten Parametern Aluminiumteile mehr besch\u00e4digen als miteinander verbinden. Au\u00dferdem bilden sich m\u00f6glicherweise auf der Oberfl\u00e4che des Werkstoffs d\u00fcnne Oxidschichten, die die Qualit\u00e4t der Schwei\u00dfnaht beeintr\u00e4chtigen.\u00a0<\/p>\n\n\n\n<p>F\u00fcr das Schwei\u00dfen von Aluminium verwenden Sie am besten die MIG- oder WIG-Methode. F\u00fcr beide nutzen Sie ein inertes Schutzgas wie Argon. Die erste Technik erm\u00f6glicht das Verbinden von Werkst\u00fccken mit einer St\u00e4rke von 1 mm und mehr. Erfahrenere Schwei\u00dfer greifen auf pulsierenden Strom zur\u00fcck, um Aluminiumteile mit einer St\u00e4rke von weniger als 1 mm zu verbinden.&nbsp;<\/p>\n\n\n\n<p>Weniger erfahrene Personen schwei\u00dfen am besten mit einem WIG-AC\/DC-Schwei\u00dfger\u00e4t. Es schwei\u00dft Aluminium mit einer maximalen St\u00e4rke von bis zu 10 mm. Zudem nutzen Sie am WIG-Schwei\u00dfger\u00e4t die Option Wechselstrom (AC), die das Schwei\u00dfbad beim Aluminiumschwei\u00dfen sauber h\u00e4lt.&nbsp;<\/p>\n\n\n\n<p><mdspan datatext=\"el1724998905960\" class=\"mdspan-comment\">Ein weiteres weitverbreitetes Metall ist Edelstahl. Wie Sie zwei daraus hergestellte Metallteile miteinander kombinieren, lesen Sie unserem Artikel zum <a href=\"https:\/\/www.expondo.de\/inspirationen\/mit-welcher-schweissmethode-kann-ich-edelstahl-schweissen\/\" target=\"_blank\" rel=\"noreferrer noopener\">Edelstahl schwei\u00dfen<\/a>.\u00a0<\/mdspan><\/p>\n\n\n\n  <div class=\"banner\">\n    <div class=\"container container--between-max-full\">\n      <img decoding=\"async\" src=\"https:\/\/www.expondo.co.uk\/cms-images\/20260612-HP-brands-banner.webp\" alt=\"\">\n    <\/div>\n    <div class=\"container banner__txt-container\">\n      <div class=\"banner__txtbox\">\n        <p class=\"banner-text\">Wir entwickeln Profi-Ausr\u00fcstung und bieten Versand &amp; Support aus Europa.<\/p>\n        <h2 class=\"promo-banner-header\" style=\"margin-bottom: 2rem;\">Unsere Marken. Unsere Standards.<\/h2>\n        <a class=\"button\" href=\"https:\/\/www.expondo.de\/search?query=\">Mehr anzeigen        <\/a>\n      <\/div>\n    <\/div>\n  <\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"6-wie-teuer-sind-professionelle-schwei%C3%9Farbeiten-\">Wie teuer sind professionelle Schwei\u00dfarbeiten?&nbsp;<\/h2>\n\n\n\n<p>Wenn Sie nicht die geeignete Ausr\u00fcstung besitzen oder zu wenig Erfahrung mit dem Schwei\u00dfen haben, dann greifen Sie auf professionelle Dienste zur\u00fcck. Profis bringen das n\u00f6tige Wissen mit, um qualitativ hochwertige Verbindungen herzustellen. Doch wie viel kostet dieser Service?&nbsp;<\/p>\n\n\n\n<p>Der Preis f\u00fcr Schwei\u00dfdienstleistungen h\u00e4ngt von vielen Faktoren ab, unter anderem die bereits genannten Erfahrungen und F\u00e4higkeiten. Dar\u00fcber hinaus wird der Preis \u00fcber die Schwei\u00dfmethode, die Art des zu verbindenden Materials, die Komplexit\u00e4t des Auftrags und sogar den Standort (in der Werkstatt oder bei der Kundschaft vor Ort) bestimmt. Am h\u00e4ufigsten nehmen Schwei\u00dfunternehmen jedoch Folgendes in ihre Preislisten auf:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Kosten f\u00fcr Anschaffung und Bearbeitung des Materials (Bohren, Schneiden, Reinigen),&nbsp;<\/li>\n\n\n\n<li>Zeitaufwand f\u00fcr die Vorbereitung und das Schwei\u00dfen selbst,&nbsp;<\/li>\n\n\n\n<li>Energieverbrauch,&nbsp;<\/li>\n\n\n\n<li>Zusatzleistungen, z.B. Malerarbeiten.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Ausschlaggebend f\u00fcr den Preis sind in der Regel die Kosten f\u00fcr die Herstellung von 1 cm Schwei\u00dfnaht. Manche Handwerksbetriebe berechnen es in Quadrat- oder Laufmetern. F\u00fcr bestimmte Formen, z. B. Tore oder Z\u00e4une, verlangen Profis normalerweise einen Festpreis f\u00fcr ein St\u00fcck des fertigen Produkts.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"7-was-ist-schwei%C3%9Fen-%E2%80%93-zusammenfassung-\">Was ist Schwei\u00dfen? \u2013 Zusammenfassung&nbsp;&nbsp;<\/h2>\n\n\n\n<p>Schwei\u00dfen ist eine g\u00e4ngige Methode, um Metalle miteinander zu verbinden. Sie wird eingesetzt, um Autos, Alltagsger\u00e4te oder sogar H\u00e4user zu bauen.&nbsp;<\/p>\n\n\n\n<p>Wenn Sie Metalle schwei\u00dfen wollen, ben\u00f6tigen Sie das richtige Werkzeug. Praktische Tipps zum Kauf der richtigen Ausstattung finden Sie in unserem Artikel zur Auswahl eines Schwei\u00dfger\u00e4ts <a href=\"https:\/\/www.expondo.de\/inspirationen\/welches-inverter-schweissgerat-sollen-sie-erwerben\/\" target=\"_blank\" rel=\"noreferrer noopener\"><mdspan datatext=\"el1724998956100\" class=\"mdspan-comment\">mit Inverter-Technologie<\/mdspan><\/a>.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fcr die Metallverarbeitung formen und schneiden Sie nicht nur Metalle, sondern f\u00fcgen diese auch zusammen. Die&hellip;<\/p>\n","protected":false},"author":11,"featured_media":26781,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_sb_is_suggestion_mode":false,"_sb_show_suggestion_boards":false,"_sb_show_comment_boards":false,"_sb_suggestion_history":"","_sb_update_block_changes":"","ub_ctt_via":"","rank_math_lock_modified_date":false,"_strive_post_notes":"532\n1.\nhttps:\/\/www.expondo.fr\/poste-a-souder\/\n\nhttps:\/\/www.expondo.co.uk\/welders\/\n\nhttps:\/\/www.expondo.it\/saldatrici-professionali\/\n\nhttps:\/\/www.expondo.se\/svetsar\/\n2.\n12\n\nhttps:\/\/www.expondo.fr\/inspirations\/le-soudage-tig-description-informations-appareilsle-soudage-tig-description-informations-appareils\/\n\nhttps:\/\/www.expondo.co.uk\/inspirations\/tig-welding-description-information-and-equipment\/\n\nhttps:\/\/www.expondo.it\/inspirazioni\/saldatura-tig-descrizione-informazioni-strumenti\/\n\nSE not yet ordered\n3.\n11\nhttps:\/\/www.expondo.fr\/inspirations\/le-soudage-migmag-description-informations-outilsle-soudage-migmag-description-informations-outils\/\n\nhttps:\/\/www.expondo.co.uk\/inspirations\/mig-mag-welding-description-information-and-equipment\/\n\nhttps:\/\/www.expondo.it\/inspirazioni\/saldatura-mig-mag-descrizione-informazioni-strumenti\/\n\nSE not ordered yet\n4.\nhttps:\/\/www.expondo.fr\/poste-a-souder\/\n\nhttps:\/\/www.expondo.co.uk\/welders\/\n\nhttps:\/\/www.expondo.it\/saldatrici-professionali\/\n\nhttps:\/\/www.expondo.se\/svetsar\/\n5.\n94\n\nhttps:\/\/www.expondo.fr\/inspirations\/soudure-de-laluminium-quel-poste-a-souder-choisir\/\n\nhttps:\/\/www.expondo.co.uk\/inspirations\/aluminium-welding-which-welder-should-you-choose\/\n\nFor IT and SE, please, leave a comment for translated KW: ID 94\n\n6.\n227\nhttps:\/\/www.expondo.fr\/inspirations\/quel-poste-a-souder-inverter-choisir-guide\/\n\nhttps:\/\/www.expondo.co.uk\/inspirations\/inverter-welding-machines-which-one-should-you-buy\/\n\nFor IT and SE, please, leave a comment for translated KW: ID 227","footnotes":""},"categories":[2795],"tags":[],"promotion":[],"class_list":["post-70143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schweissen"],"acf":[],"featured_image_src":"https:\/\/www.expondo.de\/inspirationen\/wp-content\/uploads\/2022\/01\/10020208-6.jpg","author_info":{"display_name":"Maciej Skor\u017cepo","author_link":"https:\/\/www.expondo.de\/inspirationen\/author\/maciej-skorzepo\/"},"reading_time":"7","author_thumbnail":"https:\/\/secure.gravatar.com\/avatar\/3183c3d3fa9609213d6e58e2ecd78e08?s=96&d=mm&r=g","excerpt_full":"\n<p><strong>F\u00fcr die Metallverarbeitung formen und schneiden Sie nicht nur Metalle, sondern f\u00fcgen diese auch zusammen. Die g\u00e4ngigste Methode zum Verbinden von Metallen ist das Schwei\u00dfen. Was es mit dieser Methode auf sich hat, erfahren Sie in diesem Artikel.&nbsp;<\/strong>&nbsp;<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"0-was-ist-schwei%C3%9Fen-\">Was ist Schwei\u00dfen?&nbsp;<\/h2>\n\n\n\n<p>Beim Schwei\u00dfen nutzen Sie sehr hohe Temperaturen, um Metallteile zu schmelzen, die an der Kontaktstelle eine Verbindung eingehen. Je nach Technik verwenden Sie zus\u00e4tzliche Bindemittel in Form von Elektroden, Schwei\u00dfdr\u00e4hten oder speziellen St\u00e4ben. Diese verbinden sich mit dem geschmolzenen Metall und bilden nach dem Aush\u00e4rten die Schwei\u00dfnaht.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"1-arten-und-methoden-des-schwei%C3%9Fens-\">Arten und Methoden des Schwei\u00dfens&nbsp;<\/h2>\n\n\n\n<p>F\u00fcr das Zusammenf\u00fcgen von Metallen mit Hitze wurden seit seiner Erfindung verschiedene Arten und Methoden des Schwei\u00dfens entwickelt. Sie unterscheiden sich aufgrund der verwendeten Energiequellen oder der Art der Materialverarbeitung. Nach Energiearten lassen sich folgende Schwei\u00dfarten unterscheiden:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n\n\n\n\n\n<\/ul>\n\n\n\n<p>In diesem Artikel stellen wir Ihnen das Elektroschwei\u00dfen vor. Es findet in vielen Branchen Einsatz, z. B. in der Automobilindustrie, im Maschinenbau und bei Heimwerken. Hierf\u00fcr verwenden Sie unterschiedliche <a href=\"https:\/\/www.expondo.de\/schweissgeraete\/\" target=\"_blank\" rel=\"noreferrer noopener\"><mdspan datatext=\"el1724998183304\" class=\"mdspan-comment\">Schwei\u00dfger\u00e4te<\/mdspan><\/a>. Das Elektroschwei\u00dfen wird in mehrere Methoden unterteilt: WIG, MIG\/MAG und MMA.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"2-das-wig-schwei%C3%9Fen-\">Das WIG-Schwei\u00dfen&nbsp;<\/h3>\n\n\n\n<p>F\u00fcr das WIG-Schwei\u00dfverfahren verwenden Sie im Gegensatz zu anderen Schwei\u00dfmethoden eine nicht schmelzende Wolframelektrode. Zwischen ihr und dem Werkst\u00fcck erzeugen Sie einen Lichtbogen mit einer sehr hohen Temperatur, die zum Schmelzen des Metalls erforderlich ist. F\u00fcr eine stabile Schwei\u00dfnaht wird h\u00e4ufig zus\u00e4tzliches Material in Form von Schwei\u00dfst\u00e4ben hinzugef\u00fcgt.&nbsp;<\/p>\n\n\n\n\n\n<p>Ein weiteres charakteristisches Merkmal <a href=\"https:\/\/www.expondo.de\/inspirationen\/wig-schweissen-von-den-anfaengen-bis-heute\/\" target=\"_blank\" rel=\"noreferrer noopener\"><mdspan datatext=\"el1724998458541\" class=\"mdspan-comment\">des WIG-Schwei\u00dfens<\/mdspan><\/a> ist die Verwendung von Inertgas. Es sch\u00fctzt das Schwei\u00dfbad, also das beim Erhitzen entstehende fl\u00fcssige Metall. Dadurch wird die Verbindung haltbarer und korrosionsbest\u00e4ndiger.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"3-die-migmag-schwei%C3%9Fmethode-\">Die MIG\/MAG-Schwei\u00dfmethode&nbsp;<\/h3>\n\n\n\n<p>Die <a href=\"https:\/\/www.expondo.de\/inspirationen\/mig-oder-mag-aufs-schutzgas-kommt-es-an\/\" target=\"_blank\" rel=\"noreferrer noopener\"><mdspan datatext=\"el1724998649280\" class=\"mdspan-comment\">Schwei\u00dfmethoden MIG<\/mdspan><\/a> und MAG werden oft zusammen genannt, weil sie sich nur in einer Sache unterscheiden. Bei beiden Techniken wird ein Schwei\u00dfdraht verwendet, um einen Lichtbogen zu erzeugen. Unter dem Einfluss der erzeugten W\u00e4rme schmilzt der Draht und erzeugt eine feste Schwei\u00dfnaht zwischen den Metallst\u00fccken.\u00a0<\/p>\n\n\n\n\n\n<p>Der einzige Unterschied zwischen MIG und MAG ist das verwendete Schutzgas. F\u00fcr MIG verwenden Sie Inertgase wie Argon, f\u00fcr MAG aktive Gase wie Kohlendioxid. Ersteres reagiert nicht mit dem Metall im Schwei\u00dfbad, letzteres hingegen schon. Beide haben jedoch die gleiche Aufgabe \u2013 den Schutz der Schwei\u00dfnaht vor \u00e4u\u00dferen Einfl\u00fcssen.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"4-mit-elektroden-schwei%C3%9Fen-\">Mit Elektroden Schwei\u00dfen&nbsp;<\/h3>\n\n\n\n<p>Die letzte elektrische <a href=\"https:\/\/www.expondo.de\/schweissgeraete\/\" target=\"_blank\" rel=\"noreferrer noopener\"><mdspan datatext=\"el1724998726722\" class=\"mdspan-comment\">Schwei\u00dfmethode<\/mdspan><\/a> ist MMA oder E-Hand. Daf\u00fcr verwenden Sie eine umh\u00fcllte Elektrode aus einem Metallkern und einer Ummantelung, um eine Schwei\u00dfnaht herzustellen. W\u00e4hrend des Schwei\u00dfens schmilzt der Kern und aus der Au\u00dfenh\u00fclle werden Schutzgase freigesetzt. Dabei entsteht Schlacke, die auf der Schwei\u00dfnaht zur\u00fcckbleibt.\u00a0<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"5-was-muss-ich-beim-aluminiumschwei%C3%9Fen-beachten-\">Was muss ich beim Aluminiumschwei\u00dfen beachten?&nbsp;<\/h2>\n\n\n\n<p>Beim Schwei\u00dfen verbinden Sie verschiedene Arten von Metallen und deren Legierungen miteinander. Einige Metallarten erfordern jedoch ausreichende Kenntnisse, um sicherzustellen, dass Sie den Grundwerkstoff nicht besch\u00e4digen und eine sehr haltbare Schwei\u00dfnaht erzielen. Ein hervorragendes Beispiel ist Aluminium.&nbsp;<\/p>\n\n\n\n<p>Die Schwierigkeit beim <a href=\"https:\/\/www.expondo.de\/inspirationen\/aluminium-schweissen-welches-schweissgeraet-soll-ich-waehlen\/\" target=\"_blank\" rel=\"noreferrer noopener\"><mdspan datatext=\"el1724998819883\" class=\"mdspan-comment\">Schwei\u00dfen von Aluminium<\/mdspan><\/a> ist sein relativ niedriger Schmelzpunkt. Das bedeutet, dass Sie bei schlecht eingestellten Parametern Aluminiumteile mehr besch\u00e4digen als miteinander verbinden. Au\u00dferdem bilden sich m\u00f6glicherweise auf der Oberfl\u00e4che des Werkstoffs d\u00fcnne Oxidschichten, die die Qualit\u00e4t der Schwei\u00dfnaht beeintr\u00e4chtigen.\u00a0<\/p>\n\n\n\n<p>F\u00fcr das Schwei\u00dfen von Aluminium verwenden Sie am besten die MIG- oder WIG-Methode. F\u00fcr beide nutzen Sie ein inertes Schutzgas wie Argon. Die erste Technik erm\u00f6glicht das Verbinden von Werkst\u00fccken mit einer St\u00e4rke von 1 mm und mehr. Erfahrenere Schwei\u00dfer greifen auf pulsierenden Strom zur\u00fcck, um Aluminiumteile mit einer St\u00e4rke von weniger als 1 mm zu verbinden.&nbsp;<\/p>\n\n\n\n<p>Weniger erfahrene Personen schwei\u00dfen am besten mit einem WIG-AC\/DC-Schwei\u00dfger\u00e4t. Es schwei\u00dft Aluminium mit einer maximalen St\u00e4rke von bis zu 10 mm. Zudem nutzen Sie am WIG-Schwei\u00dfger\u00e4t die Option Wechselstrom (AC), die das Schwei\u00dfbad beim Aluminiumschwei\u00dfen sauber h\u00e4lt.&nbsp;<\/p>\n\n\n\n<p><mdspan datatext=\"el1724998905960\" class=\"mdspan-comment\">Ein weiteres weitverbreitetes Metall ist Edelstahl. Wie Sie zwei daraus hergestellte Metallteile miteinander kombinieren, lesen Sie unserem Artikel zum <a href=\"https:\/\/www.expondo.de\/inspirationen\/mit-welcher-schweissmethode-kann-ich-edelstahl-schweissen\/\" target=\"_blank\" rel=\"noreferrer noopener\">Edelstahl schwei\u00dfen<\/a>.\u00a0<\/mdspan><\/p>\n\n\n\n[custom_api_shortcode]\n\n\n\n<h2 class=\"wp-block-heading\" id=\"6-wie-teuer-sind-professionelle-schwei%C3%9Farbeiten-\">Wie teuer sind professionelle Schwei\u00dfarbeiten?&nbsp;<\/h2>\n\n\n\n<p>Wenn Sie nicht die geeignete Ausr\u00fcstung besitzen oder zu wenig Erfahrung mit dem Schwei\u00dfen haben, dann greifen Sie auf professionelle Dienste zur\u00fcck. Profis bringen das n\u00f6tige Wissen mit, um qualitativ hochwertige Verbindungen herzustellen. Doch wie viel kostet dieser Service?&nbsp;<\/p>\n\n\n\n<p>Der Preis f\u00fcr Schwei\u00dfdienstleistungen h\u00e4ngt von vielen Faktoren ab, unter anderem die bereits genannten Erfahrungen und F\u00e4higkeiten. Dar\u00fcber hinaus wird der Preis \u00fcber die Schwei\u00dfmethode, die Art des zu verbindenden Materials, die Komplexit\u00e4t des Auftrags und sogar den Standort (in der Werkstatt oder bei der Kundschaft vor Ort) bestimmt. Am h\u00e4ufigsten nehmen Schwei\u00dfunternehmen jedoch Folgendes in ihre Preislisten auf:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n\n\n\n\n\n<\/ul>\n\n\n\n<p>Ausschlaggebend f\u00fcr den Preis sind in der Regel die Kosten f\u00fcr die Herstellung von 1 cm Schwei\u00dfnaht. Manche Handwerksbetriebe berechnen es in Quadrat- oder Laufmetern. F\u00fcr bestimmte Formen, z. B. Tore oder Z\u00e4une, verlangen Profis normalerweise einen Festpreis f\u00fcr ein St\u00fcck des fertigen Produkts.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"7-was-ist-schwei%C3%9Fen-%E2%80%93-zusammenfassung-\">Was ist Schwei\u00dfen? \u2013 Zusammenfassung&nbsp;&nbsp;<\/h2>\n\n\n\n<p>Schwei\u00dfen ist eine g\u00e4ngige Methode, um Metalle miteinander zu verbinden. Sie wird eingesetzt, um Autos, Alltagsger\u00e4te oder sogar H\u00e4user zu bauen.&nbsp;<\/p>\n\n\n\n<p>Wenn Sie Metalle schwei\u00dfen wollen, ben\u00f6tigen Sie das richtige Werkzeug. Praktische Tipps zum Kauf der richtigen Ausstattung finden Sie in unserem Artikel zur Auswahl eines Schwei\u00dfger\u00e4ts <a href=\"https:\/\/www.expondo.de\/inspirationen\/welches-inverter-schweissgerat-sollen-sie-erwerben\/\" target=\"_blank\" rel=\"noreferrer noopener\"><mdspan datatext=\"el1724998956100\" class=\"mdspan-comment\">mit Inverter-Technologie<\/mdspan><\/a>.\u00a0<\/p>\n","_links":{"self":[{"href":"https:\/\/www.expondo.de\/inspirationen\/wp-json\/wp\/v2\/posts\/70143"}],"collection":[{"href":"https:\/\/www.expondo.de\/inspirationen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.expondo.de\/inspirationen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.expondo.de\/inspirationen\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.expondo.de\/inspirationen\/wp-json\/wp\/v2\/comments?post=70143"}],"version-history":[{"count":7,"href":"https:\/\/www.expondo.de\/inspirationen\/wp-json\/wp\/v2\/posts\/70143\/revisions"}],"predecessor-version":[{"id":85598,"href":"https:\/\/www.expondo.de\/inspirationen\/wp-json\/wp\/v2\/posts\/70143\/revisions\/85598"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.expondo.de\/inspirationen\/wp-json\/wp\/v2\/media\/26781"}],"wp:attachment":[{"href":"https:\/\/www.expondo.de\/inspirationen\/wp-json\/wp\/v2\/media?parent=70143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.expondo.de\/inspirationen\/wp-json\/wp\/v2\/categories?post=70143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.expondo.de\/inspirationen\/wp-json\/wp\/v2\/tags?post=70143"},{"taxonomy":"promotion","embeddable":true,"href":"https:\/\/www.expondo.de\/inspirationen\/wp-json\/wp\/v2\/promotion?post=70143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}